{"id":102369,"date":"2025-05-23T18:00:19","date_gmt":"2025-05-23T17:00:19","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=102369"},"modified":"2025-05-22T16:36:09","modified_gmt":"2025-05-22T15:36:09","slug":"ntn-europe-investe-e-torna-se-fabricante-de-amortecedores","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/","title":{"rendered":"NTN Europe investe e torna-se fabricante de amortecedores"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-102378\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\" alt=\"05 - NTN Europe investe e torna se fabricante de amortecedores\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores-768x436.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/p>\n<p><strong>A <a href=\"https:\/\/www.ntn-snr.com\/\" target=\"_blank\" rel=\"noopener\">NTN Europe<\/a> entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente de reposi\u00e7\u00e3o autom\u00f3vel<\/strong><\/p>\n<p>A empresa anunciou a 20 de maio de 2025 a entrada no capital da Sociedade LTM, especialista em amortecedores do Grupo Mecatech, com uma participa\u00e7\u00e3o de 35%. A decis\u00e3o surge ap\u00f3s o sucesso comercial da sua gama de amortecedores, lan\u00e7ada sob a marca SNR no final de 2023<\/p>\n<p>&#8220;Esta participa\u00e7\u00e3o de 35% representa o trabalho realizado ao longo de quase dois anos e o que as equipas da LTM e da NTN Europe experienciam diariamente atrav\u00e9s dos seus interc\u00e2mbios&#8221;, explicou Christophe Idelon, vice-presidente de pe\u00e7as de substitui\u00e7\u00e3o autom\u00f3vel da NTN Europe.<\/p>\n<p>O investimento ir\u00e1 refor\u00e7ar a capacidade industrial da LTM, localizada na Tun\u00edsia, permitindo aumentar os volumes de produ\u00e7\u00e3o. O objetivo da NTN Europe \u00e9 posicionar-se como fabricante e parceiro de refer\u00eancia no setor, beneficiando da experi\u00eancia t\u00e9cnica da LTM e da sua pr\u00f3pria trajet\u00f3ria no segmento OE (Equipamento Original).<\/p>\n<p>&#8220;Impulsionados pela excelente din\u00e2mica industrial e comercial que surgiu desta associa\u00e7\u00e3o, agora queremos ir mais al\u00e9m e superar novas etapas para desenvolver a nossa atividade comum na produ\u00e7\u00e3o de amortecedores. Por isso decidimos investir no Grupo Mecatech. Esta posi\u00e7\u00e3o permitir-nos-\u00e1 refor\u00e7ar ainda mais nossa estreita colabora\u00e7\u00e3o&#8221;, acrescentou.<\/p>\n<p>A parceria \u00e9 igualmente valorizada pelo Grupo Mecatech: &#8220;Estamos muito satisfeitos com o resultado desta colabora\u00e7\u00e3o, iniciada h\u00e1 mais de um ano. A aquisi\u00e7\u00e3o do capital da empresa pela NTN Europe demonstra a expertise t\u00e9cnica e industrial que a LTM aperfei\u00e7oou no fabrico de amortecedores. Como fornecedor de primeiro n\u00edvel e de renome mundial, a NTN Europe traz-nos uma experi\u00eancia inestim\u00e1vel em tecnologia de Equipamento Original (OE).<\/p>\n<p>Juntos, podemos continuar a trabalhar para desenvolver a nossa produ\u00e7\u00e3o de amortecedores inovadores e de alta qualidade, principalmente para o mercado de pe\u00e7as de substitui\u00e7\u00e3o autom\u00f3vel&#8221;, afirmou Abdessalem Ben Ayed, Presidente e CEO da Mecatech.<\/p>\n<p>Com esta integra\u00e7\u00e3o, a NTN Europe passa a oferecer uma solu\u00e7\u00e3o completa aos distribuidores no conceito de &#8220;corner&#8221;, refor\u00e7ando a visibilidade de todas as suas gamas. O desenvolvimento industrial da atividade de amortecedores em territ\u00f3rio tunisino ter\u00e1 impacto positivo nas opera\u00e7\u00f5es em Fran\u00e7a e em toda a Europa, onde a empresa mant\u00e9m produ\u00e7\u00e3o e centros log\u00edsticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A NTN Europe entrou no capital&#8230;<\/p>\n","protected":false},"author":15,"featured_media":102378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[1014,6936,6935,5867,6934,12782],"class_list":["post-102369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","tag-amortecedores","tag-grupo-mecatech","tag-ltm","tag-mercado-independente","tag-ntn-europe","tag-reposicao-automovel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T17:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"NTN Europe investe e torna-se fabricante de amortecedores\",\"datePublished\":\"2025-05-23T17:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\",\"keywords\":[\"amortecedores\",\"Grupo Mecatech\",\"LTM\",\"mercado independente\",\"NTN Europe\",\"reposi\u00e7\u00e3o autom\u00f3vel\"],\"articleSection\":[\"Empresas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/\",\"name\":\"NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\",\"datePublished\":\"2025-05-23T17:00:19+00:00\",\"description\":\"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg\",\"width\":1024,\"height\":581,\"caption\":\"05 - NTN Europe investe e torna se fabricante de amortecedores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NTN Europe investe e torna-se fabricante de amortecedores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas","description":"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/","og_locale":"pt_PT","og_type":"article","og_title":"NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas","og_description":"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente","og_url":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2025-05-23T17:00:19+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"NTN Europe investe e torna-se fabricante de amortecedores","datePublished":"2025-05-23T17:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/"},"wordCount":418,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg","keywords":["amortecedores","Grupo Mecatech","LTM","mercado independente","NTN Europe","reposi\u00e7\u00e3o autom\u00f3vel"],"articleSection":["Empresas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/","url":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/","name":"NTN Europe investe e torna-se fabricante de amortecedores - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg","datePublished":"2025-05-23T17:00:19+00:00","description":"A NTN Europe entrou no capital da LTM e passa a produzir amortecedores, refor\u00e7ando a sua presen\u00e7a no mercado independente","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2025\/05\/NTN-Europe-investe-e-torna-se-fabricante-de-amortecedores.jpg","width":1024,"height":581,"caption":"05 - NTN Europe investe e torna se fabricante de amortecedores"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/ntn-europe-investe-e-torna-se-fabricante-de-amortecedores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"NTN Europe investe e torna-se fabricante de amortecedores"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/102369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=102369"}],"version-history":[{"count":5,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/102369\/revisions"}],"predecessor-version":[{"id":102380,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/102369\/revisions\/102380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/102378"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=102369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=102369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=102369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}