{"id":116449,"date":"2026-05-11T12:30:55","date_gmt":"2026-05-11T11:30:55","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=116449"},"modified":"2026-05-07T18:46:47","modified_gmt":"2026-05-07T17:46:47","slug":"febi-amplia-gama-com-amortecedores-para-ligeiros","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/","title":{"rendered":"febi amplia gama com amortecedores para ligeiros"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-116500\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg\" alt=\"febi amplia gama com amortecedores para ligeiros\" width=\"1024\" height=\"580\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj-768x435.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>A <a href=\"https:\/\/www.febi.com\/\" target=\"_blank\" rel=\"noopener\">febi<\/a> expandiu a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros, num lan\u00e7amento que d\u00e1 continuidade \u00e0 experi\u00eancia da marca nas \u00e1reas de dire\u00e7\u00e3o e suspens\u00e3o<\/strong><\/p>\n<p>Segundo a marca, esta entrada no segmento n\u00e3o representa uma nova dire\u00e7\u00e3o, mas antes &#8220;um passo l\u00f3gico&#8221; na evolu\u00e7\u00e3o do portef\u00f3lio, com uma solu\u00e7\u00e3o desenvolvida especificamente para o aftermarket independente.<\/p>\n<p>Os novos amortecedores febi foram concebidos para responder \u00e0s necessidades das oficinas, combinando desempenho equivalente ao equipamento original, precis\u00e3o de encaixe e qualidade consistente.<\/p>\n<p>&#8220;Cada amortecedor febi \u00e9 submetido a testes rigorosos e passa por um exigente processo de aprova\u00e7\u00e3o de tr\u00eas fases para garantir um comportamento de amortecimento est\u00e1vel, controlo preciso e conforto duradouro. Esta abordagem de engenharia apoia uma instala\u00e7\u00e3o de confian\u00e7a, reduz as devolu\u00e7\u00f5es e proporciona uma experi\u00eancia de condu\u00e7\u00e3o que os clientes podem, realmente, sentir&#8221;, afirmou a febi em comunicado.<\/p>\n<p>A gama conta j\u00e1 com mais de 500 refer\u00eancias, abrangendo mais de 60.000 aplica\u00e7\u00f5es para ve\u00edculos ligeiros e comerciais ligeiros. A febi referiu ainda que novas refer\u00eancias ser\u00e3o introduzidas de forma cont\u00ednua, com base em dados OE, para acompanhar os modelos mais relevantes nos diferentes mercados.<\/p>\n<p>A instala\u00e7\u00e3o em oficina foi tamb\u00e9m considerada no desenvolvimento da gama, com design de n\u00edvel OE, identifica\u00e7\u00e3o clara do produto e acesso ao partsfinder atrav\u00e9s de c\u00f3digo QR.<\/p>\n<p>A embalagem premium, o revestimento por eletrodeposi\u00e7\u00e3o em preto acetinado e as cintas de prote\u00e7\u00e3o resistentes completam a proposta, procurando facilitar a log\u00edstica, reduzir devolu\u00e7\u00f5es e refor\u00e7ar a confian\u00e7a no ponto de venda.<\/p>\n<p>Com esta introdu\u00e7\u00e3o, a febi acrescenta mais um componente essencial ao seu portef\u00f3lio, mantendo a aposta em solu\u00e7\u00f5es orientadas para qualidade, engenharia e aplica\u00e7\u00e3o pr\u00e1tica em oficina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A febi expandiu a sua gama&#8230;<\/p>\n","protected":false},"author":15,"featured_media":116500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[1014,626,4061,15092,3494],"class_list":["post-116449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","tag-amortecedores","tag-febi","tag-gama-de-produtos","tag-pos-venda-independente","tag-veiculos-ligeiros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T11:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"febi amplia gama com amortecedores para ligeiros\",\"datePublished\":\"2026-05-11T11:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/nfgjfgj.jpg\",\"keywords\":[\"amortecedores\",\"febi\",\"gama de produtos\",\"p\u00f3s-venda independente\",\"Ve\u00edculos ligeiros\"],\"articleSection\":[\"Empresas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/\",\"name\":\"febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/nfgjfgj.jpg\",\"datePublished\":\"2026-05-11T11:30:55+00:00\",\"description\":\"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/nfgjfgj.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/nfgjfgj.jpg\",\"width\":1024,\"height\":580,\"caption\":\"febi amplia gama com amortecedores para ligeiros\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/febi-amplia-gama-com-amortecedores-para-ligeiros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"febi amplia gama com amortecedores para ligeiros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas","description":"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/","og_locale":"pt_PT","og_type":"article","og_title":"febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas","og_description":"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros","og_url":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2026-05-11T11:30:55+00:00","og_image":[{"width":1024,"height":580,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"febi amplia gama com amortecedores para ligeiros","datePublished":"2026-05-11T11:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/"},"wordCount":326,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg","keywords":["amortecedores","febi","gama de produtos","p\u00f3s-venda independente","Ve\u00edculos ligeiros"],"articleSection":["Empresas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/","url":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/","name":"febi amplia gama com amortecedores para ligeiros - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg","datePublished":"2026-05-11T11:30:55+00:00","description":"A febi expandiu recentemente a sua gama de produtos com a introdu\u00e7\u00e3o de amortecedores para ve\u00edculos ligeiros","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2026\/05\/nfgjfgj.jpg","width":1024,"height":580,"caption":"febi amplia gama com amortecedores para ligeiros"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/febi-amplia-gama-com-amortecedores-para-ligeiros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"febi amplia gama com amortecedores para ligeiros"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/116449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=116449"}],"version-history":[{"count":6,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/116449\/revisions"}],"predecessor-version":[{"id":116502,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/116449\/revisions\/116502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/116500"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=116449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=116449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=116449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}