{"id":17902,"date":"2020-12-28T10:00:11","date_gmt":"2020-12-28T10:00:11","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=17902"},"modified":"2020-12-28T09:31:29","modified_gmt":"2020-12-28T09:31:29","slug":"lg-electronics-e-magna-international-aliadas-numa-joint-venture","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/","title":{"rendered":"LG Electronics e Magna International aliadas numa joint venture"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17900 size-full\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg\" alt=\"12 - LG-Electronics-e-Magna-International\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International-768x436.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>A LG Electronics e a Magna International Inc. anunciaram uma joint venture para fabricar e-motores, inversores e carregadores de bordo e, para alguns fabricantes, sistemas de e-drive relacionados para apoiar a crescente mudan\u00e7a global em dire\u00e7\u00e3o \u00e0 eletrifica\u00e7\u00e3o de ve\u00edculos.<\/strong><\/p>\n<p>A nova empresa, cujo nome provis\u00f3rio \u00e9 LG Magna e-Powertrain, une a for\u00e7a da Magna em sistemas de transmiss\u00e3o el\u00e9trica e produ\u00e7\u00e3o autom\u00f3vel de classe mundial com a expertise da LG no desenvolvimento de componentes para e-motores e inversores, acelerando o crescimento de ambos os parceiros no mercado do powertrain el\u00e9trico.<\/p>\n<p>A joint venture vem permitir que as duas empresas continuem a aumentar a sua oferta de produtos powetrain el\u00e9trico aproveitando as tecnologias, recursos de engenharia e pegadas globais j\u00e1 existentes. Espera-se que o mercado de e-motores, inversores e sistemas el\u00e9tricos tenha um crescimento significativo at\u00e9 2030, sendo que esta joint venture ter\u00e1 como alvo este mercado global de r\u00e1pido crescimento com um portef\u00f3lio de elevada qualidade.<\/p>\n<p>A LG tem experi\u00eancia comprovada no desenvolvimento de componentes de ve\u00edculos el\u00e9tricos, principalmente para os modelos Chevrolet Bolt EV e Jaguar I-PACE. A LG vem assim ajudar a acelerar o tempo de lan\u00e7amento de novos produtos da Magna no mercado e a escala de produ\u00e7\u00e3o de componentes el\u00e9tricos. Por sua vez, a integra\u00e7\u00e3o de software e sistemas \u00e9 uma das compet\u00eancias que a Magna traz para este empreendimento.<\/p>\n<p>\u201cEsta parceria est\u00e1 totalmente em linha com a nossa estrat\u00e9gia de vanguarda no mercado el\u00e9trico para apoiar os fabricantes de autom\u00f3veis com um portef\u00f3lio diversificado e de classe mundial\u201d, afirma o presidente e novo CEO da Magna, Swamy Kotagiri. \u201cAo combinar os nossos pontos fortes, esperamos ganhar efici\u00eancia nos investimentos e velocidade de lan\u00e7amento no mercado atrav\u00e9s de sinergias de valoriza\u00e7\u00e3o, ao mesmo tempo em que continuamos a capitalizar na acelera\u00e7\u00e3o do mercado do powertrain el\u00e9trico.\u201d<\/p>\n<p>\u201cCada vez mais, os fabricantes precisam de ser disruptivos para manter posi\u00e7\u00f5es de lideran\u00e7a no mercado el\u00e9trico e, atrav\u00e9s deste acordo, a LG vai entrar numa nova fase do seu neg\u00f3cio de componentes de autom\u00f3veis, o que se afigura como uma oportunidade de crescimento de enorme potencial\u201d, refere o Dr. Kim Jin-yong, presidente da LG Electronics Vehicle Component Solutions Company. \u201cAcreditamos que a uni\u00e3o do nosso know-how com a extensa hist\u00f3ria da Magna vai transformar rapidamente o espa\u00e7o do powertrain el\u00e9trico de forma mais r\u00e1pida.\u201d<\/p>\n<p>A joint venture incluir\u00e1 mais de mil colaboradores provenientes da unidades da LG nos EUA, Coreia do Sul e China. O processo dever\u00e1 ser conclu\u00eddo em julho de 2021, estando sujeito a uma s\u00e9rie de condi\u00e7\u00f5es, incluindo a aprova\u00e7\u00e3o por parte dos acionistas da LG e o cumprimento de todos os regulamentos necess\u00e1rios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A LG Electronics e a Magna&#8230;<\/p>\n","protected":false},"author":15,"featured_media":17900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[2506,2507],"class_list":["post-17902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","tag-lg-electronics","tag-magna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"A LG Electronics e a Magna...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-28T10:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"LG Electronics e Magna International aliadas numa joint venture\",\"datePublished\":\"2020-12-28T10:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/\"},\"wordCount\":492,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LG-Electronics-e-Magna-International.jpg\",\"keywords\":[\"LG Electronics\",\"Magna\"],\"articleSection\":[\"Empresas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/\",\"name\":\"LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LG-Electronics-e-Magna-International.jpg\",\"datePublished\":\"2020-12-28T10:00:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LG-Electronics-e-Magna-International.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/LG-Electronics-e-Magna-International.jpg\",\"width\":1024,\"height\":581,\"caption\":\"Ground roads and the city skyline of Chongqing; Shutterstock ID 561479467; Purchase Order: -; Producer Name: -\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LG Electronics e Magna International aliadas numa joint venture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/","og_locale":"pt_PT","og_type":"article","og_title":"LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas","og_description":"A LG Electronics e a Magna...","og_url":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2020-12-28T10:00:11+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"LG Electronics e Magna International aliadas numa joint venture","datePublished":"2020-12-28T10:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/"},"wordCount":492,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg","keywords":["LG Electronics","Magna"],"articleSection":["Empresas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/","url":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/","name":"LG Electronics e Magna International aliadas numa joint venture - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg","datePublished":"2020-12-28T10:00:11+00:00","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2020\/12\/LG-Electronics-e-Magna-International.jpg","width":1024,"height":581,"caption":"Ground roads and the city skyline of Chongqing; Shutterstock ID 561479467; Purchase Order: -; Producer Name: -"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/lg-electronics-e-magna-international-aliadas-numa-joint-venture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"LG Electronics e Magna International aliadas numa joint venture"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/17902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=17902"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/17902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/17900"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=17902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=17902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=17902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}