{"id":26018,"date":"2021-12-08T18:00:52","date_gmt":"2021-12-08T18:00:52","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=26018"},"modified":"2021-12-08T09:17:29","modified_gmt":"2021-12-08T09:17:29","slug":"gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/","title":{"rendered":"&#8220;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&#8221;, Elsa Reis, CASA"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26012\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg\" alt=\"12 - conflitos-casa\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa-300x170.jpeg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa-150x85.jpeg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa-768x436.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/p>\n<p><strong>Para esclarecer os profissionais das lojas de pe\u00e7as, oficinas de repara\u00e7\u00e3o e consumidor final, sobre a nova Lei das Garantias, Elsa Reis, diretora do <a href=\"https:\/\/www.arbitragemauto.pt\/\" target=\"_blank\" rel=\"noopener\">CASA<\/a>, responde <\/strong><strong>a algumas das quest\u00f5es mais comummente colocadas<\/strong><\/p>\n<p>O CASA tem realizado um trabalho cont\u00ednuo, prestando informa\u00e7\u00e3o jur\u00eddica \u00e0s empresas e aos consumidores, promovendo a media\u00e7\u00e3o e disponibilizando a peritagem por uma entidade isenta e independente com quem tem protocolo exclusivo. Continua a sugerir as melhores pr\u00e1ticas \u00e0s empresas que lhes permitam diminuir o n\u00famero de reclama\u00e7\u00f5es e uma gest\u00e3o mais eficaz das reclama\u00e7\u00f5es que v\u00e3o surgindo.<\/p>\n<p><strong>Qual o \u00e2mbito de aplica\u00e7\u00e3o da nova Lei das Garantias?<\/strong><br \/>\nO novo regime aplicar-se-\u00e1:<br \/>\na) Aos contratos de compra e venda celebrados entre consumidores e profissionais, incluindo os contratos celebrados para o fornecimento de bens a fabricar ou a produzir;<br \/>\nb) Aos bens fornecidos no \u00e2mbito de um contrato de empreitada ou de outra presta\u00e7\u00e3o de servi\u00e7os, bem como \u00e0 loca\u00e7\u00e3o de bens;<br \/>\nc) Aos conte\u00fados ou servi\u00e7os digitais que estejam incorporados em bens, ou que com eles estejam interligados, (\u2026) e sejam fornecidos com os bens nos termos de um contrato de compra e venda, independentemente de os conte\u00fados ou servi\u00e7os digitais serem fornecidos pelo profissional ou por um terceiro.<\/p>\n<p><strong>As pe\u00e7as reconstru\u00eddas tamb\u00e9m est\u00e3o abrangidas pela nova Lei das Garantias?<\/strong><br \/>\nSim, a nova lei das garantias introduz o conceito de bens reconstru\u00eddos e confere-lhes um prazo de garantia de 3 anos, tal como nos bens novos. Um bem reconstru\u00eddo \u00e9 aquele que foi objeto de utiliza\u00e7\u00e3o pr\u00e9via ou devolu\u00e7\u00e3o e que, ap\u00f3s inspe\u00e7\u00e3o, prepara\u00e7\u00e3o, verifica\u00e7\u00e3o e testagem por um profissional, \u00e9 novamente colocado para venda no mercado nessa qualidade.<\/p>\n<p><strong>Que diferen\u00e7as existem entre clientes finais<\/strong><br \/>\ne empresas em termos de prazos, responsabilidades e procedimentos?<br \/>\nQuando falamos em \u201cclientes finais\u201d devemos entender como consumidores. Ou seja, a pessoa singular que adquire um bem ou um servi\u00e7o para fins n\u00e3o profissionais. Se o cliente preencher estes requisitos, ent\u00e3o aplicar-se-\u00e1 a Lei das Garantias, gozando de 3 anos de garantia no caso de adquirir um bem novo ou 18 meses se adquirir um bem usado. Caso contr\u00e1rio, aplicar-se-\u00e1 o C\u00f3digo Civil que prev\u00ea uma garantia de bom funcionamento por 6 meses, se outro prazo n\u00e3o for convencionado pelas partes.<\/p>\n<p>Para l\u00ear toda a entrevista clique <a href=\"https:\/\/www.yumpu.com\/pt\/document\/read\/66010465\/jornal-das-oficinas-192\/30\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para esclarecer os profissionais das lojas&#8230;<\/p>\n","protected":false},"author":15,"featured_media":26012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[138],"class_list":["post-26018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","tag-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&quot;, Elsa Reis, CASA - Jornal das Oficinas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&quot;, Elsa Reis, CASA - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"Para esclarecer os profissionais das lojas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-08T18:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"&#8220;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&#8221;, Elsa Reis, CASA\",\"datePublished\":\"2021-12-08T18:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/conflitos-casa.jpeg\",\"keywords\":[\"CASA\"],\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/\",\"name\":\"\\\"Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz\\\", Elsa Reis, CASA - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/conflitos-casa.jpeg\",\"datePublished\":\"2021-12-08T18:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/conflitos-casa.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/conflitos-casa.jpeg\",\"width\":1024,\"height\":581,\"caption\":\"12 - conflitos-casa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&#8221;, Elsa Reis, CASA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz\", Elsa Reis, CASA - Jornal das Oficinas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/","og_locale":"pt_PT","og_type":"article","og_title":"\"Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz\", Elsa Reis, CASA - Jornal das Oficinas","og_description":"Para esclarecer os profissionais das lojas...","og_url":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2021-12-08T18:00:52+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"&#8220;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&#8221;, Elsa Reis, CASA","datePublished":"2021-12-08T18:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/"},"wordCount":421,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg","keywords":["CASA"],"articleSection":["Entrevistas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/","url":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/","name":"\"Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz\", Elsa Reis, CASA - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg","datePublished":"2021-12-08T18:00:52+00:00","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2021\/12\/conflitos-casa.jpeg","width":1024,"height":581,"caption":"12 - conflitos-casa"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/gestao-de-reclamacoes-mais-eficaz-elsa-reis-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"&#8220;Gest\u00e3o de reclama\u00e7\u00f5es mais eficaz&#8221;, Elsa Reis, CASA"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/26018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=26018"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/26018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/26012"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=26018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=26018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=26018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}