{"id":60187,"date":"2023-01-06T12:00:27","date_gmt":"2023-01-06T12:00:27","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=60187"},"modified":"2023-01-06T08:47:27","modified_gmt":"2023-01-06T08:47:27","slug":"brembo-sensify-premiado-nos-lingxuan-awards","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/","title":{"rendered":"Brembo Sensify premiado nos Lingxuan Awards"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60182\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\" alt=\"01 - Brembo Sensify premiado nos Lingxuan Awards\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards-768x436.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong><a href=\"https:\/\/www.sensify.brembo.com\/\" target=\"_blank\" rel=\"noopener\">Brembo Sensify<\/a>, o sistema de travagem inteligente pioneiro da <a href=\"https:\/\/www.brembo.com\/en\" target=\"_blank\" rel=\"noopener\">Brembo<\/a>, recebeu um pr\u00e9mio de ouro da categoria &#8220;chassis forward-looking&#8221; por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan<\/strong><\/p>\n<p>Os Pr\u00e9mios Lingxuan (nomeadamente o Pr\u00e9mio da Ind\u00fastria de Pe\u00e7as Autom\u00f3veis da China) t\u00eam como objetivo encorajar empresas mais proeminentes e intervenientes na ind\u00fastria de pe\u00e7as para autom\u00f3veis e oferecer aos fabricantes de autom\u00f3veis um cen\u00e1rio centrado na tecnologia da cadeia de fornecimento.<\/p>\n<p>O j\u00fari dos Pr\u00e9mios Lingxuan \u00e9 composto principalmente por chefes de compras e I&amp;D de OEMs e o Brembo Sensify destacou-se entre 161 candidaturas de 129 empresas.<\/p>\n<p>Brembo Sensify evoluiu naturalmente da heran\u00e7a e do know-how da Brembo. Combina a atual carteira de produtos Brembo de pin\u00e7as, discos e materiais de fri\u00e7\u00e3o com tecnologia digital e intelig\u00eancia artificial para criar uma plataforma flex\u00edvel e evolutiva que inclui software, algoritmos de previs\u00e3o e gest\u00e3o de dados para controlar o sistema de travagem digitalmente, e personalizar individualmente a resposta de travagem para aumentar o prazer de condu\u00e7\u00e3o.<\/p>\n<p>&#8220;Estamos orgulhosos e honrados por este prestigioso pr\u00e9mio, o Gold Award atribu\u00eddo a Brembo Sensify representa o reconhecimento pela ind\u00fastria autom\u00f3vel na China de como a Brembo est\u00e1 empenhada em fornecer solu\u00e7\u00f5es de ponta, inovadoras, inteligentes e sustent\u00e1veis&#8221;, disse Daniele Schillaci, Chief Executive Officer da Brembo.<\/p>\n<p>No futuro, Brembo ir\u00e1 apostar no sistema Sensify na China, para potenciar o desenvolvimento da eletrifica\u00e7\u00e3o e digitaliza\u00e7\u00e3o da ind\u00fastria autom\u00f3vel chinesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brembo Sensify, o sistema de travagem&#8230;<\/p>\n","protected":false},"author":15,"featured_media":60182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[283,3667,3668,3672,3671,3669,3670],"class_list":["post-60187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","tag-brembo","tag-brembo-sensify","tag-chassis-forward-looking","tag-chief-executive-officer","tag-daniele-schillaci","tag-premio-de-ouro","tag-premios-lingxuan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria &quot;chassis forward-looking&quot; por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria &quot;chassis forward-looking&quot; por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-06T12:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"Brembo Sensify premiado nos Lingxuan Awards\",\"datePublished\":\"2023-01-06T12:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\",\"keywords\":[\"Brembo\",\"Brembo Sensify\",\"chassis forward-looking\",\"Chief Executive Officer\",\"Daniele Schillaci\",\"pr\u00e9mio de ouro\",\"Pr\u00e9mios Lingxuan\"],\"articleSection\":[\"Empresas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/\",\"name\":\"Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\",\"datePublished\":\"2023-01-06T12:00:27+00:00\",\"description\":\"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria \\\"chassis forward-looking\\\" por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg\",\"width\":1024,\"height\":581,\"caption\":\"01 - Brembo Sensify premiado nos Lingxuan Awards\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/brembo-sensify-premiado-nos-lingxuan-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brembo Sensify premiado nos Lingxuan Awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas","description":"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria \"chassis forward-looking\" por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/","og_locale":"pt_PT","og_type":"article","og_title":"Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas","og_description":"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria \"chassis forward-looking\" por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan","og_url":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2023-01-06T12:00:27+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"Brembo Sensify premiado nos Lingxuan Awards","datePublished":"2023-01-06T12:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/"},"wordCount":272,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg","keywords":["Brembo","Brembo Sensify","chassis forward-looking","Chief Executive Officer","Daniele Schillaci","pr\u00e9mio de ouro","Pr\u00e9mios Lingxuan"],"articleSection":["Empresas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/","url":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/","name":"Brembo Sensify premiado nos Lingxuan Awards - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg","datePublished":"2023-01-06T12:00:27+00:00","description":"O Brembo Sensify recebeu um pr\u00e9mio de ouro da categoria \"chassis forward-looking\" por ocasi\u00e3o da 7\u00aa Cerim\u00f3nia de Pr\u00e9mios Lingxuan","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/01\/Brembo-Sensify-premiado-nos-Lingxuan-Awards.jpg","width":1024,"height":581,"caption":"01 - Brembo Sensify premiado nos Lingxuan Awards"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/brembo-sensify-premiado-nos-lingxuan-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Brembo Sensify premiado nos Lingxuan Awards"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/60187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=60187"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/60187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/60182"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=60187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=60187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=60187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}