{"id":72535,"date":"2023-09-28T18:30:28","date_gmt":"2023-09-28T17:30:28","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535"},"modified":"2023-09-27T17:53:35","modified_gmt":"2023-09-27T16:53:35","slug":"como-transportar-mercadorias-termossensiveis-em-seguranca","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/como-transportar-mercadorias-termossensiveis-em-seguranca\/","title":{"rendered":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-72490\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png\" alt=\"09 - Como transportar mercadorias termossensiveis 1\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1-300x170.png 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1-150x85.png 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1-768x436.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil devido a solu\u00e7\u00e3o inovadora de controlo e acompanhamento da cadeia de frio disponibilizada pela <a href=\"https:\/\/pt.eurowag.com\/\" target=\"_blank\" rel=\"noopener\">Eurowag<\/a><\/strong><\/p>\n<p>Muitos setores, como, por exemplo, a sa\u00fade e a ind\u00fastria alimentar, enfrentam legisla\u00e7\u00f5es rigorosas para garantir que as mercadorias termossens\u00edveis sejam mantidas nas condi\u00e7\u00f5es adequadas durante o seu transporte.<\/p>\n<p>A Eurowag, a empresa europeia l\u00edder em solu\u00e7\u00f5es digitais para o transporte rodovi\u00e1rio, reconhecida pela sua excel\u00eancia em solu\u00e7\u00f5es de gest\u00e3o de frotas, estende agora o seu compromisso ao lan\u00e7ar uma solu\u00e7\u00e3o abrangente de monitoriza\u00e7\u00e3o da cadeia de frio. O transporte de cargas delicadas, incluindo produtos farmac\u00eauticos, qu\u00edmicos, alimentos e produtos cosm\u00e9ticos, enfrenta desafios \u00fanicos que exigem uma abordagem especializada. Com a nova solu\u00e7\u00e3o da Eurowag, as empresas podem minimizar os riscos e maximizar a efici\u00eancia, proporcionando uma experi\u00eancia de transporte confi\u00e1vel aos seus clientes.<\/p>\n<p>\u201cEm geral, existem dois tipos de bens de transporte. Os que n\u00e3o requerem aten\u00e7\u00e3o especial, que s\u00e3o f\u00e1ceis de armazenar e n\u00e3o t\u00eam uma necessidade constante de controlo durante o seu transporte. Depois, h\u00e1 o segundo tipo \u2013 carga de transporte que necessita de um manuseamento cuidadoso \u2013 e que, muitas vezes, s\u00e3o indesejadas por muitas transportadoras devido ao risco acrescido que implica o seu transporte. Este tipo de mercadorias requerem uma aten\u00e7\u00e3o especial durante o transporte, que consiste, por exemplo, na estabilidade da temperatura\u201d, refere Carlos Guerra, Country Manager da Eurowag em Portugal.<\/p>\n<p>O controlo da temperatura durante o transporte \u00e9 vital e obrigat\u00f3rio para muitas ind\u00fastrias. A utiliza\u00e7\u00e3o de um sistema de monitoriza\u00e7\u00e3o tornou-se uma especifica\u00e7\u00e3o padr\u00e3o no transporte com temperatura controlada e faz parte da legisla\u00e7\u00e3o de muitos pa\u00edses.<\/p>\n<p>Como complemento da solu\u00e7\u00e3o de localiza\u00e7\u00e3o e gest\u00e3o de frotas Eurowag, as funcionalidades disponibilizadas como monitoriza\u00e7\u00e3o em tempo real, alertas e relat\u00f3rios com base nas informa\u00e7\u00f5es recebidas dos sensores de temperatura, permitem reagir rapidamente se a mesma flutuar para al\u00e9m do que \u00e9 suposto, aumentar a satisfa\u00e7\u00e3o e qualidade de servi\u00e7o a clientes com a entrega da mercadoria nas melhores condi\u00e7\u00f5es, mitigar reclama\u00e7\u00f5es atrav\u00e9s de relat\u00f3rios detalhados dos registos de temperatura realizados nessa rota, bem como, evitar perdas pela reposi\u00e7\u00e3o de mercadorias estragadas ou indemniza\u00e7\u00f5es a clientes.<\/p>\n<p>\u201cA solu\u00e7\u00e3o Eurowag oferece uma prote\u00e7\u00e3o eficaz contra a perda de mercadorias perec\u00edveis devido a temperaturas incorretas. Entre os principais benef\u00edcios da solu\u00e7\u00e3o de controlo de temperatura de carga disponibilizada pela Eurowag, destaca-se a garantia da qualidade do produto, a conformidade com a legisla\u00e7\u00e3o em vigor, a redu\u00e7\u00e3o de desperd\u00edcio, melhoria da efici\u00eancia, satisfa\u00e7\u00e3o dos clientes, a redu\u00e7\u00e3o de riscos e um processo de transporte transparente e de confian\u00e7a\u201d, refere Jorge Almeida, Business Development Manager da Eurowag em Portugal.<\/p>\n<p>Para implementar a monitoriza\u00e7\u00e3o da cadeia de frio em ve\u00edculos ou atrelados, a Eurowag oferece a integra\u00e7\u00e3o diretamente em sistemas de refrigera\u00e7\u00e3o como Thermoking ou Carrier ou a instala\u00e7\u00e3o de term\u00f3metros atrav\u00e9s de conex\u00e3o Bluethoot com unidades EVA ou Vetronics.<\/p>\n<p>A Eurowag continua a liderar a inova\u00e7\u00e3o no setor da gest\u00e3o de frotas, disponibilizando solu\u00e7\u00f5es que garantem a seguran\u00e7a, conformidade e efici\u00eancia em todas as etapas do transporte rodovi\u00e1rio de mercadorias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garantir a seguran\u00e7a e a qualidade&#8230;<\/p>\n","protected":false},"author":15,"featured_media":72490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[2785,6274],"class_list":["post-72535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pesados","tag-eurowag","tag-transporte-mercadorias-termosensiveis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/?p=72535\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/?p=72535\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-28T17:30:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a?\",\"datePublished\":\"2023-09-28T17:30:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Como-transportar-mercadorias-termossensiveis-1.png\",\"keywords\":[\"Eurowag\",\"Transporte mercadorias termosens\u00edveis\"],\"articleSection\":[\"Pesados\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535\",\"name\":\"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Como-transportar-mercadorias-termossensiveis-1.png\",\"datePublished\":\"2023-09-28T17:30:28+00:00\",\"description\":\"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Como-transportar-mercadorias-termossensiveis-1.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Como-transportar-mercadorias-termossensiveis-1.png\",\"width\":1024,\"height\":581,\"caption\":\"09 - Como transportar mercadorias termossensiveis 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?p=72535#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas","description":"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535","og_locale":"pt_PT","og_type":"article","og_title":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas","og_description":"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora","og_url":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2023-09-28T17:30:28+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png","type":"image\/png"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a?","datePublished":"2023-09-28T17:30:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535"},"wordCount":600,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png","keywords":["Eurowag","Transporte mercadorias termosens\u00edveis"],"articleSection":["Pesados"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535","url":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535","name":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a? - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png","datePublished":"2023-09-28T17:30:28+00:00","description":"Garantir a seguran\u00e7a e a qualidade de mercadorias de temperatura controlada durante o transporte \u00e9 agora mais f\u00e1cil com a solu\u00e7\u00e3o inovadora","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/?p=72535"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Como-transportar-mercadorias-termossensiveis-1.png","width":1024,"height":581,"caption":"09 - Como transportar mercadorias termossensiveis 1"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/?p=72535#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Como transportar mercadorias termossens\u00edveis em seguran\u00e7a?"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/72535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=72535"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/72535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/72490"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=72535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=72535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=72535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}