{"id":73089,"date":"2023-10-11T16:00:38","date_gmt":"2023-10-11T15:00:38","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=73089"},"modified":"2023-10-10T18:53:48","modified_gmt":"2023-10-10T17:53:48","slug":"global-mobility-call-expo-esta-quase-a-chegar","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/","title":{"rendered":"Global Mobility Call Expo est\u00e1 quase a chegar!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73083\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\" alt=\"09 - Global Mobility Call Expo esta quase a chegar\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar-768x436.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o <a href=\"https:\/\/www.ifema.es\/en\/global-mobility-call\/tickets?gclid=Cj0KCQjw7JOpBhCfARIsAL3bobcBNhyjl_s5sREtuqcjRwr8tQ1UeRWmpi0JuAt7jQ3ggtOJqT1ofCMaAsAEEALw_wcB&amp;gclsrc=aw.ds\" target=\"_blank\" rel=\"noopener\">Global Mobility Call Expo<\/a>, de 24 a 26 de outubro, a apresentar as suas principais novidades e solu\u00e7\u00f5es de desenvolvimento e inova\u00e7\u00e3o tecnol\u00f3gica para o futuro da mobilidade<\/strong><\/p>\n<p>A forte representa\u00e7\u00e3o setorial e empresarial que estar\u00e1 presente na segunda edi\u00e7\u00e3o da Global Mobility Call consolida-a como o \u00fanico evento monogr\u00e1fico de mobilidade sustent\u00e1vel da agenda internacional. Os n\u00fameros desta edi\u00e7\u00e3o, que viu crescer a participa\u00e7\u00e3o em 76% relativamente a 2022, assim como a presen\u00e7a de empresas internacionais que representam nesta edi\u00e7\u00e3o 25% do total, frente a 10% da edi\u00e7\u00e3o anterior, confirmam este evento na maior plataforma de exposi\u00e7\u00e3o, networking e gera\u00e7\u00e3o de novas oportunidades de neg\u00f3cios e colabora\u00e7\u00e3o p\u00fablico-privada para a mobilidade sustent\u00e1vel.<\/p>\n<p>Todas as modalidades de transporte e setores afins estar\u00e3o presentes neste encontro internacional, desde transporte em autocarro, ferrovi\u00e1rio de larga dist\u00e2ncia e de proximidade, metro, a\u00e9reo, mar\u00edtimo, mobilidade partilhada, infraestruturas, constru\u00e7\u00e3o e energ\u00e9ticas. Adicionalmente, integram-se nesta oferta empresas de grande consumo, banca, tecnol\u00f3gicas, de servi\u00e7os de mobilidade, especialistas em sustentabilidade, gabinetes jur\u00eddicos, seguran\u00e7a rodovi\u00e1ria, assim como administra\u00e7\u00f5es p\u00fablicas como munic\u00edpios, governos regionais e nacionais com as suas \u00e1reas de planifica\u00e7\u00e3o urban\u00edstica e desenvolvimento de cidades.<\/p>\n<p>O evento reunir\u00e1 10.000 profissionais participantes de alto perfil profissional; 60% ocupa cargos de alta dire\u00e7\u00e3o, al\u00e9m de outros 15.000 que se estima participem atrav\u00e9s da plataforma digital.<\/p>\n<p><strong>Inova\u00e7\u00e3o e grandes novidades no espa\u00e7o GMC Expo.<br \/>\n<\/strong>O desenvolvimento e a inova\u00e7\u00e3o tecnol\u00f3gica, direcionadas \u00e0s solu\u00e7\u00f5es de mobilidade ser\u00e3o as grandes protagonistas desta nova convocat\u00f3ria que re\u00fane a oferta de mais de um a centena de empresas expositoras e partners, que apresentar\u00e3o as suas principais novidades.<\/p>\n<p>Entre outras propostas, conta-se com a apresenta\u00e7\u00e3o do novo autom\u00f3vel 24H Lemans que se revelar\u00e1 no dia 24 de outubro, e a presen\u00e7a do primeiro aerot\u00e1xi espanhol impulsionado por drones.<\/p>\n<p>Adicionalmente, a EDP, Main Itinerary Partner do evento, trar\u00e1 um simulador de F\u00f3rmula E; a Fundaci\u00f3n ONCE apresentar\u00e1 um robot guia para personas invisuais; a SETGA dar\u00e1 protagonismo \u00e0 VIAK, sistemas luminosos peatonais; a GSS POWER destacar\u00e1 os seus carregadores ultrarr\u00e1pidos para ve\u00edculos; a Teralco apresentar\u00e1 \u201cCommutie\u201d, a sua plataforma colaborativa que promove a mobilidade sustent\u00e1vel; a Sisas promover\u00e1 o seu sistema de seguran\u00e7a \u201cPedestrian Save\u201d e o seu dispositivo de seguran\u00e7a nos carris para bicicletas \u201cECO Bike\u201d; e a CIIMA-UP4 chega como a uni\u00e3o entre o conhecimento, atrav\u00e9s de 4 universidades polit\u00e9cnicas, e o setor industrial, com solu\u00e7\u00f5es de mobilidade e transporte para o futuro.<\/p>\n<p>Esperam-se ainda muitas apresenta\u00e7\u00f5es exclusivas de novidades durante os 3 dias do evento, que se ir\u00e3o anunciando nos pr\u00f3ximos dias.<\/p>\n<p>A maior plataforma de exposi\u00e7\u00e3o, networking e oportunidades de neg\u00f3cio.<\/p>\n<p>O espa\u00e7o GMC Expo contar\u00e1 com a presen\u00e7a de 104 empresas, num incremento de 76% em rela\u00e7\u00e3o ao ano passado, no que ser\u00e1 o maior ponto de encontro dirigido a fomentar a colabora\u00e7\u00e3o p\u00fablico-privada entre as administra\u00e7\u00f5es p\u00fablicas e o setor empresarial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No total ser\u00e3o 104 empresas as&#8230;<\/p>\n","protected":false},"author":15,"featured_media":73083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[6373,6372],"class_list":["post-73089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-24-a-26-de-outubro","tag-global-mobility-call-expo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-11T15:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"Global Mobility Call Expo est\u00e1 quase a chegar!\",\"datePublished\":\"2023-10-11T15:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/\"},\"wordCount\":552,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\",\"keywords\":[\"24 a 26 de outubro\",\"Global Mobility Call Expo\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/\",\"name\":\"Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\",\"datePublished\":\"2023-10-11T15:00:38+00:00\",\"description\":\"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg\",\"width\":1024,\"height\":581,\"caption\":\"09 - Global Mobility Call Expo esta quase a chegar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/global-mobility-call-expo-esta-quase-a-chegar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Global Mobility Call Expo est\u00e1 quase a chegar!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas","description":"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/","og_locale":"pt_PT","og_type":"article","og_title":"Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas","og_description":"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro","og_url":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2023-10-11T15:00:38+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"Global Mobility Call Expo est\u00e1 quase a chegar!","datePublished":"2023-10-11T15:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/"},"wordCount":552,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg","keywords":["24 a 26 de outubro","Global Mobility Call Expo"],"articleSection":["Mercado"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/","url":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/","name":"Global Mobility Call Expo est\u00e1 quase a chegar! - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg","datePublished":"2023-10-11T15:00:38+00:00","description":"No total ser\u00e3o 104 empresas as que estar\u00e3o presentes no espa\u00e7o Global Mobility Call Expo, de 24 a 26 de outubro","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2023\/09\/Global-Mobility-Call-Expo-esta-quase-a-chegar.jpg","width":1024,"height":581,"caption":"09 - Global Mobility Call Expo esta quase a chegar"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/global-mobility-call-expo-esta-quase-a-chegar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Global Mobility Call Expo est\u00e1 quase a chegar!"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/73089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=73089"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/73089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/73083"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=73089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=73089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=73089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}