{"id":77001,"date":"2024-01-16T14:00:42","date_gmt":"2024-01-16T14:00:42","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=77001"},"modified":"2024-01-15T14:22:28","modified_gmt":"2024-01-15T14:22:28","slug":"kroftools-lanca-novos-produtos-para-o-aftermarket","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/","title":{"rendered":"Kroftools lan\u00e7a novos produtos para o aftermarket"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-77012\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\" alt=\"01 - Kroftools lanca novos produtos para o aftermarket\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket-300x170.jpg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket-150x85.jpg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket-768x436.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Para come\u00e7ar o ano em grande, a <a href=\"https:\/\/www.kroftools.com\/pt\/\" target=\"_blank\" rel=\"noopener\">Kroftools<\/a> decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis no site da marca. Entre eles, os novos m\u00f3dulos de ferramenta e um novo jogo de chaves de remo\u00e7\u00e3o do filtro do \u00f3leo<\/strong><\/p>\n<p>Confira abaixo todas as carater\u00edsticas destes novos lan\u00e7amentos:<\/p>\n<p><strong>8361 &#8211; M\u00d3DULO CHAVES BOCA ISOLADAS 24-32MM 4PCS<\/strong><\/p>\n<p>Descri\u00e7\u00e3o:<\/p>\n<ul>\n<li>IEC60900 para trabalhos com tens\u00e3o at\u00e9 1000V AC<\/li>\n<li>Chaves com certifica\u00e7\u00e3o VDE<\/li>\n<li>Fabricado em cromo van\u00e1dio<\/li>\n<li>Tamanho das chaves: 24mm, 27mm, 30mm, 32mm<\/li>\n<\/ul>\n<p><strong>8360 &#8211; M\u00d3DULO CHAVES CAIXA 1\/2\u201d ISOLADA 20PCS<\/strong><\/p>\n<p>Descri\u00e7\u00e3o:<\/p>\n<ul>\n<li>IEC60900 para trabalhos com tens\u00e3o at\u00e9 1000V AC<\/li>\n<li>Chave caixa e roquete isolados com certifica\u00e7\u00e3o VDE<\/li>\n<\/ul>\n<p>Composi\u00e7\u00e3o:<\/p>\n<p>(13x) Chaves VDE de 1\/2&#8243;: 10mm, 11mm, 12mm, 13mm, 14mm, 16mm, 17mm, 18mm, 19mm, 21mm, 22mm, 24mm, 27mm<\/p>\n<p>(4x) Chaves VDE de 1\/2&#8243;: H4*80mm, H5*80mm, H6*80mm, H8*80mm<\/p>\n<p>(1x) Aumento VDE de 1\/2&#8243;: 250mm<\/p>\n<p>(1x) Chave em T VDE de 1\/2&#8243;: 200mm<\/p>\n<p>(1x) Roquete VDE de 1\/2&#8243;: 250mm<\/p>\n<p><strong>8362 &#8211; M\u00d3DULO CHAVES BOCA ISOLADAS 6-21MM 14PCS<\/strong><\/p>\n<p>Descri\u00e7\u00e3o:<\/p>\n<ul>\n<li>IEC60900 para trabalhos com tens\u00e3o at\u00e9 1000V AC<\/li>\n<li>Chaves com certifica\u00e7\u00e3o VDE<\/li>\n<li>Fabricado em cromo van\u00e1dio<\/li>\n<li>Tamanho das chaves: 6mm, 7mm, 8mm, 9mm, 10mm, 11mm, 12mm, 13mm, 14mm, 15mm, 16mm, 17mm, 19mm, 21mm<\/li>\n<\/ul>\n<p><strong>8363 &#8211; M\u00d3DULO CHAVES EM L HEX. ISOLADAS 3-12MM 7PCS<\/strong><\/p>\n<p>Descri\u00e7\u00e3o:<\/p>\n<ul>\n<li>IEC60900 para trabalhos com tens\u00e3o at\u00e9 1000V AC<\/li>\n<li>Chaves com certifica\u00e7\u00e3o VDE<\/li>\n<li>Fabricado em cromo van\u00e1dio<\/li>\n<li>Tamanho das chaves hexag.: 3mm, 4mm, 5mm, 6mm, 8mm, 10mm, 12mm<\/li>\n<\/ul>\n<p><strong>4088 &#8211; JOGO CHAVES REMO\u00c7\u00c3O FILTRO \u00d3LEO 7PCS<\/strong><\/p>\n<p>Composi\u00e7\u00e3o: Conjunto de chaves de p\u00e9 de galo: 24mm, 27mm, 29mm, 30mm, 32mm, 36mm e 38mm com acionamento de 3\/8&#8243;<\/p>\n<p>Aplica\u00e7\u00e3o: Audi: A6 3.2 TSi V6 (2004)<\/p>\n<p>BMW Mini: M52 s\u00e9ries 3 e 5, M60 6 cilindros s\u00e9ries 5, 7, 8, M73 12 cilindros s\u00e9ries 7 e 8<\/p>\n<p>Ford: Transit 2.2, 2.4, 3.2 (2006), Fiesta 1.4, 1.6 TDCi<\/p>\n<p>Mercedes-Benz: Classe A, 220d, E220d, M604, C250d, E250d, M605, E300d, M606 mb. MB Transporter M616, 116MB, 100<\/p>\n<p>Renault: 1.5, 1.9, 2.2, 2.5 dci<\/p>\n<p>Seat: Ibiza (a partir de 1993)<\/p>\n<p>\u0160koda: Fabia (a partir de 1999) quando equipados com motores a gasolina 1.4 16v<\/p>\n<p>Opel: Vectra B di 16v (a partir de 1998), Astra\/Zafira, Astra-G \/Corsa-B<\/p>\n<p>Volkswagen: Lupo 1.2 TDi, Touareg TDi, 2.0, 2.2 TDi, Polo 1.2, Polo (a partir de 1995), Golf (a partir de 1992), Transporter T5 1.9 (2004)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para come\u00e7ar o ano em grande,&#8230;<\/p>\n","protected":false},"author":15,"featured_media":77012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[147,7099,42,2771],"class_list":["post-77001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equipamentos","tag-ferramentas","tag-jogo-de-chaves","tag-kroftools","tag-novos-produtos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T14:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"Kroftools lan\u00e7a novos produtos para o aftermarket\",\"datePublished\":\"2024-01-16T14:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\",\"keywords\":[\"Ferramentas\",\"jogo de chaves\",\"KROFtools\",\"novos produtos\"],\"articleSection\":[\"Equipamentos\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/\",\"name\":\"Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\",\"datePublished\":\"2024-01-16T14:00:42+00:00\",\"description\":\"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg\",\"width\":1024,\"height\":581,\"caption\":\"01 - Kroftools lanca novos produtos para o aftermarket\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/kroftools-lanca-novos-produtos-para-o-aftermarket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kroftools lan\u00e7a novos produtos para o aftermarket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas","description":"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/","og_locale":"pt_PT","og_type":"article","og_title":"Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas","og_description":"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis","og_url":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2024-01-16T14:00:42+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"Kroftools lan\u00e7a novos produtos para o aftermarket","datePublished":"2024-01-16T14:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/"},"wordCount":391,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg","keywords":["Ferramentas","jogo de chaves","KROFtools","novos produtos"],"articleSection":["Equipamentos"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/","url":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/","name":"Kroftools lan\u00e7a novos produtos para o aftermarket - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg","datePublished":"2024-01-16T14:00:42+00:00","description":"Para come\u00e7ar o ano em grande, a Kroftools decidiu adicionar cinco produtos novos ao seu portf\u00f3lio que j\u00e1 se encontram dispon\u00edveis","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/01\/Kroftools-lanca-novos-produtos-para-o-aftermarket.jpg","width":1024,"height":581,"caption":"01 - Kroftools lanca novos produtos para o aftermarket"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/kroftools-lanca-novos-produtos-para-o-aftermarket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Kroftools lan\u00e7a novos produtos para o aftermarket"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/77001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=77001"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/77001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/77012"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=77001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=77001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=77001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}