{"id":86714,"date":"2024-06-20T12:30:52","date_gmt":"2024-06-20T11:30:52","guid":{"rendered":"https:\/\/jornaldasoficinas.com\/pt\/?p=86714"},"modified":"2024-06-19T18:15:39","modified_gmt":"2024-06-19T17:15:39","slug":"schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket","status":"publish","type":"post","link":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/","title":{"rendered":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86717\" src=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\" alt=\"05 - Schaeffler e Grupo Serca criam iniciativa verde no aftermarket\" width=\"1024\" height=\"581\" srcset=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg 1024w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket-300x170.jpeg 300w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket-150x85.jpeg 150w, https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket-768x436.jpeg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/p>\n<p><strong>&#8220;Complete the Circle&#8221; \u00e9 uma nova a\u00e7\u00e3o conjunta entre a <a href=\"https:\/\/www.schaeffler.es\/pt\/\" target=\"_blank\" rel=\"noopener\">Schaeffler<\/a> e o <a href=\"https:\/\/www.serca.es\/\" target=\"_blank\" rel=\"noopener\">Grupo Serca,<\/a> que visa identificar as empresas com maior compromisso ambiental no mercado<\/strong><\/p>\n<p>&#8220;A sustentabilidade ambiental \u00e9 uma necessidade priorit\u00e1ria no setor autom\u00f3vel. Os fabricantes de componentes e grupos de distribui\u00e7\u00e3o t\u00eam a responsabilidade de contribuir para o futuro do planeta atrav\u00e9s do desenvolvimento de pol\u00edticas sustent\u00e1veis a todos os n\u00edveis. Mas tamb\u00e9m t\u00eam a possibilidade de transmitir o seu conhecimento e experi\u00eancia aos restantes intervenientes da cadeia de valor do p\u00f3s-venda, como os distribuidores e oficinas&#8221;, come\u00e7ou por afirmar o Grupo Serca.<\/p>\n<p>O Grupo Schaeffler, especialista mundial no desenvolvimento e fabrico de componentes e sistemas autom\u00f3veis, e o Grupo Serca, especialista na distribui\u00e7\u00e3o p\u00f3s-venda na Pen\u00ednsula Ib\u00e9rica, partilham o objetivo de estender a mensagem da sustentabilidade para al\u00e9m da sua pr\u00f3pria atividade.<\/p>\n<p>Fruto deste ponto de vista comum, ambas as empresas uniram for\u00e7as e criaram a iniciativa &#8220;Complete the Circle&#8221;, uma a\u00e7\u00e3o conjunta que procura reduzir o impacto no ambiente da atividade di\u00e1ria dos distribuidores e das oficinas de repara\u00e7\u00e3o e manuten\u00e7\u00e3o de ve\u00edculos.<\/p>\n<p>Este &#8220;Completar o c\u00edrculo&#8221; (tradu\u00e7\u00e3o em portugu\u00eas), incentiva as mais de 2 mil empresas que comp\u00f5em a comunidade do Grupo SERCA (entre distribuidores e oficinas) a tomar consci\u00eancia sobre de que forma devem agir em benef\u00edcio da sustentabilidade ambiental dos seus neg\u00f3cios, mostrando-lhes como podem cuidar do planeta e contribuir para a constru\u00e7\u00e3o de um futuro melhor para todos.<\/p>\n<p>Para tal, desenvolveram um question\u00e1rio online que lhes permite conhecer o n\u00edvel de compromisso ambiental do seu neg\u00f3cio, bem como ter acesso a um aconselhamento especializado que permite implementar medidas espec\u00edficas de melhoria. Medidas que, em conjunto, se traduzem, por exemplo, na redu\u00e7\u00e3o de milhares de toneladas de CO2.<\/p>\n<p>&#8220;Complete the Circle&#8221; \u00e9 uma medida dirigida exclusivamente \u00e0 comunidade do Grupo SERCA que servir\u00e1 como amostra de refer\u00eancia para fornecer informa\u00e7\u00f5es valiosas sobre o n\u00edvel de conhecimento das pequenas e m\u00e9dias empresas empresas do setor do p\u00f3s-venda autom\u00f3vel no que diz respeito \u00e0 sustentabilidade ambiental.<\/p>\n<p>A iniciativa decorrer\u00e1 durante todo o ver\u00e3o de 2024. Depois de conclu\u00edda, a Schaeffler e o Grupo Serca ir\u00e3o divulgar os resultados obtidos, atribuindo placas de reconhecimento a todas as empresas que revelarem ter um compromisso s\u00e9rio com a sustentabilidade.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Complete the Circle&#8221; \u00e9 uma nova&#8230;<\/p>\n","protected":false},"author":15,"featured_media":86717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[9591,2689,9589,9590,1840,3240],"class_list":["post-86714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","tag-complete-the-circle","tag-grupo-serca","tag-iniciativa-verde","tag-politicas-sustentaveis","tag-schaeffler","tag-sustentabilidade-ambiental"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas<\/title>\n<meta name=\"description\" content=\"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas\" \/>\n<meta property=\"og:description\" content=\"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal das Oficinas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloficinas\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T11:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o JO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:site\" content=\"@jornaloficinas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o JO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o JO\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\"},\"headline\":\"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket\",\"datePublished\":\"2024-06-20T11:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/\"},\"wordCount\":426,\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\",\"keywords\":[\"Complete the Circle\",\"Grupo Serca\",\"iniciativa verde\",\"pol\u00edticas sustent\u00e1veis\",\"Schaeffler\",\"Sustentabilidade ambiental\"],\"articleSection\":[\"Empresas\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/\",\"name\":\"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\",\"datePublished\":\"2024-06-20T11:30:52+00:00\",\"description\":\"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg\",\"width\":1024,\"height\":581,\"caption\":\"05 - Schaeffler e Grupo Serca criam iniciativa verde no aftermarket\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"name\":\"Jornal das Oficinas\",\"description\":\"Jornal independente do Aftermarket Autom\u00f3vel em Portugal\",\"publisher\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#organization\",\"name\":\"Jornal das Oficinas\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"contentUrl\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/wp-content\\\/uploads\\\/logoJO-SEO.png\",\"width\":285,\"height\":450,\"caption\":\"Jornal das Oficinas\"},\"image\":{\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jornaloficinas\",\"https:\\\/\\\/x.com\\\/jornaloficinas\",\"https:\\\/\\\/www.instagram.com\\\/jornal_oficinas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jornal-das-oficinas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbQZBqtcvV-oSQrr7RzINGg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/#\\\/schema\\\/person\\\/a38eef5de2c41d9e7c9ac10141afddf3\",\"name\":\"Reda\u00e7\u00e3o JO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Reda\u00e7\u00e3o JO\"},\"url\":\"https:\\\/\\\/jornaldasoficinas.com\\\/pt\\\/author\\\/joredacao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas","description":"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/","og_locale":"pt_PT","og_type":"article","og_title":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas","og_description":"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio","og_url":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/","og_site_name":"Jornal das Oficinas","article_publisher":"https:\/\/www.facebook.com\/jornaloficinas","article_published_time":"2024-06-20T11:30:52+00:00","og_image":[{"width":1024,"height":581,"url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o JO","twitter_card":"summary_large_image","twitter_creator":"@jornaloficinas","twitter_site":"@jornaloficinas","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o JO","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#article","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/"},"author":{"name":"Reda\u00e7\u00e3o JO","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3"},"headline":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket","datePublished":"2024-06-20T11:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/"},"wordCount":426,"publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg","keywords":["Complete the Circle","Grupo Serca","iniciativa verde","pol\u00edticas sustent\u00e1veis","Schaeffler","Sustentabilidade ambiental"],"articleSection":["Empresas"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/","url":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/","name":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket - Jornal das Oficinas","isPartOf":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#primaryimage"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#primaryimage"},"thumbnailUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg","datePublished":"2024-06-20T11:30:52+00:00","description":"A nova a\u00e7\u00e3o conjunta entre a Schaeffler e o Grupo Serca visa identificar as empresas com maior compromisso ambiental no neg\u00f3cio","breadcrumb":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#primaryimage","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/2024\/05\/Schaeffler-e-Grupo-Serca-criam-iniciativa-verde-no-aftermarket.jpeg","width":1024,"height":581,"caption":"05 - Schaeffler e Grupo Serca criam iniciativa verde no aftermarket"},{"@type":"BreadcrumbList","@id":"https:\/\/jornaldasoficinas.com\/pt\/schaeffler-e-grupo-serca-criam-iniciativa-verde-para-o-aftermarket\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornaldasoficinas.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Schaeffler e Grupo Serca criam iniciativa \u201cverde\u201d para o aftermarket"}]},{"@type":"WebSite","@id":"https:\/\/jornaldasoficinas.com\/pt\/#website","url":"https:\/\/jornaldasoficinas.com\/pt\/","name":"Jornal das Oficinas","description":"Jornal independente do Aftermarket Autom\u00f3vel em Portugal","publisher":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornaldasoficinas.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/jornaldasoficinas.com\/pt\/#organization","name":"Jornal das Oficinas","url":"https:\/\/jornaldasoficinas.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","contentUrl":"https:\/\/jornaldasoficinas.com\/pt\/wp-content\/uploads\/logoJO-SEO.png","width":285,"height":450,"caption":"Jornal das Oficinas"},"image":{"@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jornaloficinas","https:\/\/x.com\/jornaloficinas","https:\/\/www.instagram.com\/jornal_oficinas\/","https:\/\/www.linkedin.com\/company\/jornal-das-oficinas\/","https:\/\/www.youtube.com\/channel\/UCbQZBqtcvV-oSQrr7RzINGg"]},{"@type":"Person","@id":"https:\/\/jornaldasoficinas.com\/pt\/#\/schema\/person\/a38eef5de2c41d9e7c9ac10141afddf3","name":"Reda\u00e7\u00e3o JO","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71f2fa71737ad68a84fea94bc708ddac8ea5b0c4788dc2ad202f3ccb2887742f?s=96&d=wp_user_avatar&r=g","caption":"Reda\u00e7\u00e3o JO"},"url":"https:\/\/jornaldasoficinas.com\/pt\/author\/joredacao\/"}]}},"_links":{"self":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/86714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/comments?post=86714"}],"version-history":[{"count":0,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/posts\/86714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media\/86717"}],"wp:attachment":[{"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/media?parent=86714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/categories?post=86714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornaldasoficinas.com\/pt\/wp-json\/wp\/v2\/tags?post=86714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}